{"id":10788,"date":"2024-10-23T20:46:08","date_gmt":"2024-10-24T03:46:08","guid":{"rendered":"https:\/\/evhnews.com\/?p=10788"},"modified":"2024-10-23T20:46:08","modified_gmt":"2024-10-24T03:46:08","slug":"la-faa-publie-une-regle-finale-pour-la-certification-de-la-formation-des-pilotes-de-taxis-aeriens","status":"publish","type":"post","link":"https:\/\/evhnews.com\/fr\/2024\/10\/23\/la-faa-publie-une-regle-finale-pour-la-certification-de-la-formation-des-pilotes-de-taxis-aeriens\/","title":{"rendered":"La FAA publie une r\u00e8gle finale pour la formation et la certification des pilotes de taxi a\u00e9rien"},"content":{"rendered":"<p><strong>La r\u00e8gle de la Federal Aviation Administration (FAA) est consid\u00e9r\u00e9e comme la derni\u00e8re pi\u00e8ce du puzzle pour l'introduction en toute s\u00e9curit\u00e9 des taxis a\u00e9riens\/eVTOL dans le syst\u00e8me national de l'espace a\u00e9rien \u00e0 court terme.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Par Joe Macey AAM International<\/p>\n<p><strong>L'administration f\u00e9d\u00e9rale de l'aviation (FAA) a r\u00e9v\u00e9l\u00e9 qu'elle \u00e9tait pr\u00eate \u00e0 accueillir des taxis a\u00e9riens, des livraisons de fret et toute une s\u00e9rie d'op\u00e9rations dans les zones urbaines et rurales.<\/strong><\/p>\n<p>Il s'agira de la premi\u00e8re cat\u00e9gorie d'a\u00e9ronefs civils enti\u00e8rement nouvelle depuis l'introduction des h\u00e9licopt\u00e8res dans les ann\u00e9es 1940.<\/p>\n<p>L'agence a publi\u00e9 une r\u00e8gle finale concernant les qualifications et la formation que les instructeurs et les pilotes doivent poss\u00e9der pour piloter des a\u00e9ronefs de cette cat\u00e9gorie \"powered-lift\", qui pr\u00e9sentent des caract\u00e9ristiques \u00e0 la fois des avions et des h\u00e9licopt\u00e8res.<\/p>\n<p>La r\u00e8gle traite \u00e9galement de leurs exigences op\u00e9rationnelles, notamment des altitudes minimales de s\u00e9curit\u00e9 et de la visibilit\u00e9 requise. Cette r\u00e8gle est la derni\u00e8re pi\u00e8ce du puzzle qui permettra d'introduire ces a\u00e9ronefs en toute s\u00e9curit\u00e9 \u00e0 court terme. Les possibilit\u00e9s d'utilisation d'a\u00e9ronefs \u00e0 sustentation motoris\u00e9e sont vastes : transport de passagers dans les zones urbaines, op\u00e9rations court-courriers telles que les services d'ambulance a\u00e9rienne et les op\u00e9rations de fret, et, \u00e0 terme, desserte potentielle de communaut\u00e9s plus petites.<\/p>\n<p>L'administrateur de la FAA, Mike Whitaker, a d\u00e9clar\u00e9\u00a0<em>\"La FAA continuera \u00e0 donner la priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 de notre syst\u00e8me alors que nous travaillons \u00e0 l'int\u00e9gration transparente de technologies et d'op\u00e9rations innovantes. Cette r\u00e8gle finale fournit le cadre n\u00e9cessaire pour permettre aux a\u00e9ronefs \u00e0 sustentation motoris\u00e9e d'op\u00e9rer en toute s\u00e9curit\u00e9 dans notre espace a\u00e9rien. Les a\u00e9ronefs \u00e0 sustentation motoris\u00e9e constituent la premi\u00e8re nouvelle cat\u00e9gorie d'a\u00e9ronefs depuis pr\u00e8s de 80 ans et cette r\u00e8gle historique ouvrira la voie \u00e0 des op\u00e9rations de mobilit\u00e9 a\u00e9rienne avanc\u00e9e (AAM) \u00e0 grande \u00e9chelle \u00e0 l'avenir\".<\/em><\/p>\n<p>La FAA a pr\u00e9c\u00e9demment d\u00e9termin\u00e9 qu'elle pouvait certifier les v\u00e9hicules \u00e0 propulsion \u00e9lectrique en utilisant les r\u00e9glementations existantes et a mis \u00e0 jour d'autres r\u00e9glementations afin que les taxis a\u00e9riens puissent \u00eatre utilis\u00e9s \u00e0 des fins commerciales. L'ann\u00e9e derni\u00e8re, l'agence a publi\u00e9 un plan d'action pour le fonctionnement des v\u00e9hicules de mobilit\u00e9 a\u00e9rienne urbaine, qui constitue un \u00e9l\u00e9ment cl\u00e9 dans la maturation du concept global de l'AAM.<\/p>\n<p>Une nouvelle r\u00e8gle de formation et de qualification des pilotes \u00e9tait n\u00e9cessaire car les r\u00e9glementations existantes ne prenaient pas en compte cette nouvelle cat\u00e9gorie d'a\u00e9ronefs, qui peuvent d\u00e9coller et atterrir verticalement comme un h\u00e9licopt\u00e8re et voler comme un avion en vol de croisi\u00e8re. La r\u00e8gle fournit un cadre complet pour la certification du premier groupe d'instructeurs et de pilotes d'a\u00e9ronefs \u00e0 sustentation motoris\u00e9e.<\/p>\n<p>La r\u00e8gle :<\/p>\n<ul>\n<li>Modifie de nombreuses r\u00e9glementations existantes et \u00e9tablit une r\u00e9glementation f\u00e9d\u00e9rale sp\u00e9ciale en mati\u00e8re d'aviation (SFAR) avec de nouvelles exigences pour faciliter la certification et la formation des instructeurs et des pilotes.<\/li>\n<li>Applique les exigences d'exploitation des h\u00e9licopt\u00e8res \u00e0 certaines phases de vol et adopte une approche bas\u00e9e sur les performances pour certaines r\u00e8gles d'exploitation.<\/li>\n<li>Elle permet aux pilotes de s'entra\u00eener \u00e0 la conduite d'un engin \u00e0 moteur avec un seul jeu de commandes de vol, alors que les anciennes r\u00e8gles exigent deux commandes de vol - une pour l'\u00e9l\u00e8ve et une pour l'instructeur.\n<p>... Notes du SP,<\/p>\n<p>#EVHNews, #FAA, #SFAR, #eVTOL, #<em>Mobilit\u00e9 a\u00e9rienne avanc\u00e9e,<\/em><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>The Federal Aviation Administration (FAA) rule is seen as the final piece in the puzzle&#8230;<\/p>","protected":false},"author":165558846,"featured_media":10790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"two_page_speed":[],"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[688379954],"tags":[688387321,688386225,688387319,688387320,688386537],"class_list":["post-10788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flying-cars-electric-hybrid-aviation","tag-advanced-air-mobility","tag-evhnews-2","tag-faa","tag-sfar","tag-evtol"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-150x150.jpg?crop=1",150,150,true],"medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-300x168.jpg",300,168,true],"medium_large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-768x429.jpg",640,358,true],"large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",640,358,false],"1536x1536":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"2048x2048":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"trp-custom-language-flag":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-18x10.jpg",18,10,true],"newspack-article-block-landscape-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"newspack-article-block-portrait-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",900,503,false],"newspack-article-block-square-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"newspack-article-block-landscape-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",800,447,false],"newspack-article-block-portrait-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-square-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",800,447,false],"newspack-article-block-landscape-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-portrait-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",450,251,false],"newspack-article-block-square-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-landscape-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",400,223,false],"newspack-article-block-portrait-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",300,168,false],"newspack-article-block-square-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",400,223,false],"newspack-article-block-landscape-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",200,112,false],"newspack-article-block-portrait-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",150,84,false],"newspack-article-block-square-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",200,112,false],"newspack-article-block-uncropped":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"enternews-featured":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"enternews-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-720x475.jpg?crop=1",720,475,true],"enternews-thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-480x315.jpg?crop=1",480,315,true],"tenweb_optimizer_mobile":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-600x335.jpg",600,335,true],"tenweb_optimizer_tablet":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-768x429.jpg",768,429,true]},"author_info":{"display_name":"EVHNews","author_link":"https:\/\/evhnews.com\/fr\/author\/evhnews\/"},"category_info":"<a href=\"https:\/\/evhnews.com\/fr\/category\/aviation-electrique-hybride\/voitures-volantes-aviation-electrique-hybride\/\" rel=\"category tag\">Electric &amp; Hybrid Aerospace &amp; VTOL Aircrafts<\/a>","tag_info":"Electric &amp; Hybrid Aerospace &amp; VTOL Aircrafts","comment_count":"0","jetpack_featured_media_url":"https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbbbdx-2O0","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/users\/165558846"}],"replies":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/comments?post=10788"}],"version-history":[{"count":2,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10788\/revisions"}],"predecessor-version":[{"id":10791,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10788\/revisions\/10791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/media\/10790"}],"wp:attachment":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/media?parent=10788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/categories?post=10788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/tags?post=10788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}