{"id":10792,"date":"2024-10-23T20:52:56","date_gmt":"2024-10-24T03:52:56","guid":{"rendered":"https:\/\/evhnews.com\/?p=10792"},"modified":"2024-10-23T20:52:56","modified_gmt":"2024-10-24T03:52:56","slug":"eve-lance-un-portefeuille-de-services-apres-vente-pour-evtols","status":"publish","type":"post","link":"https:\/\/evhnews.com\/fr\/2024\/10\/23\/eve-lance-un-portefeuille-de-services-apres-vente-pour-evtols\/","title":{"rendered":"Eve pr\u00e9sente un portefeuille de services apr\u00e8s-vente pour les eVTOLs"},"content":{"rendered":"<p><strong>La solution int\u00e9gr\u00e9e de service \u00e0 la client\u00e8le d'Eve pour les eVTOLs offrira des services complets, une assistance \u00e0 la client\u00e8le experte et des solutions op\u00e9rationnelles.<\/strong><\/p>\n<p>By\u00a0<strong>Joe Macey<\/strong> AAM International<\/p>\n<p><strong>Eve Air Mobility a lanc\u00e9 son portefeuille de services apr\u00e8s-vente enti\u00e8rement int\u00e9gr\u00e9s pour des op\u00e9rations de mobilit\u00e9 a\u00e9rienne urbaine (UAM) efficaces et s\u00fbres \u00e0 l'occasion du salon MRO Europe qui s'est tenu \u00e0 Barcelone.<\/strong><\/p>\n<p>Eve TechCare est une suite pionni\u00e8re de solutions tout-en-un con\u00e7ues pour rationaliser les op\u00e9rations eVTOL en fournissant les services les plus complets de l'industrie, une assistance client\u00e8le experte et des solutions op\u00e9rationnelles de pointe.<\/p>\n<p>Johann Bordais, directeur g\u00e9n\u00e9ral d'Eve, a d\u00e9clar\u00e9 ;\u00a0<em>\"Chez Eve, notre objectif va au-del\u00e0 du d\u00e9veloppement et de la production d'un eVTOL ; nous adoptons une approche holistique du march\u00e9 en cr\u00e9ant une suite de solutions pour traiter les aspects n\u00e9cessaires qui feront de la mobilit\u00e9 a\u00e9rienne urbaine une r\u00e9alit\u00e9. Avec Eve TechCare, nous garantissons \u00e0 nos clients la meilleure disponibilit\u00e9 op\u00e9rationnelle des appareils tout en optimisant les co\u00fbts d'exploitation.<\/em><\/p>\n<p><em>\"Notre objectif est d'offrir \u00e0 nos clients tout ce dont ils ont besoin \u00e0 partir du moment o\u00f9 ils re\u00e7oivent leur avion\".<\/em><\/p>\n<p>S'appuyant sur les 55 ans d'histoire d'Embraer et sur son expertise de l'industrie a\u00e9rospatiale, Eve TechCare offre une mani\u00e8re unique de servir les clients avec une empreinte mondiale et une pr\u00e9sence locale. Le portefeuille de services apr\u00e8s-vente comprend une assistance et des solutions techniques, des services MRO, des pi\u00e8ces d\u00e9tach\u00e9es et des solutions de batteries, ainsi que des services de formation et des solutions d'exploitation en vol, auxquels les op\u00e9rateurs auront acc\u00e8s par le biais d'une plateforme num\u00e9rique.<\/p>\n<p>Luiz Mauad, vice-pr\u00e9sident des services \u00e0 la client\u00e8le chez Eve, a ajout\u00e9 ;\u00a0<em>\"Notre portefeuille est con\u00e7u pour l'efficacit\u00e9 et la s\u00e9curit\u00e9 op\u00e9rationnelles avec une approche unique centr\u00e9e sur le client. Nous avons d\u00e9velopp\u00e9 ces solutions sur la base de notre expertise a\u00e9rospatiale et de nos diverses interactions avec nos clients et partenaires. Le r\u00e9sultat est une offre unique en son genre qui permettra aux eVTOL de nos clients de continuer \u00e0 voler avec un taux de disponibilit\u00e9 \u00e9lev\u00e9.<\/em><\/p>\n<p><em>\"Nous nous r\u00e9jouissons de cette nouvelle \u00e9tape dans les services \u00e0 la client\u00e8le d'Eve, qui nous permettra de discuter davantage de nos offres de services avec nos clients et de leur recommander les meilleures solutions pour leurs activit\u00e9s\".<\/em><\/p>\n<p>Les solutions de service et de soutien d'Eve TechCare couvriront tous les aspects op\u00e9rationnels n\u00e9cessaires \u00e0 l'exploitation quotidienne des eVTOL. Cela comprend l'acc\u00e8s \u00e0 un centre d'assistance client\u00e8le 24h\/24 et 7j\/7, la formation des pilotes et des m\u00e9caniciens, le soutien \u00e0 l'entr\u00e9e en service, les publications techniques et op\u00e9rationnelles, les services de mat\u00e9riel et de batteries, la surveillance de l'\u00e9tat de l'a\u00e9ronef et les services MRO.<\/p>\n<p>&nbsp;<\/p>\n<p>#EVHNews, #Eve, #TechCare, #eVTOL, #Urban Air Mobility<\/p>","protected":false},"excerpt":{"rendered":"<p>Eve&#8217;s integrated customer service solution for eVTOLs will offer comprehensive services, expert customer support, and&#8230;<\/p>","protected":false},"author":165558846,"featured_media":10794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"two_page_speed":[],"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[688379954,688386715],"tags":[688387322,688386225,688387323,688386537,688386728],"class_list":["post-10792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flying-cars-electric-hybrid-aviation","category-new-ev-battery-technology","tag-eve","tag-evhnews-2","tag-techcare","tag-evtol","tag-urban-air-mobility"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-150x150.png?crop=1",150,150,true],"medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-300x182.png",300,182,true],"medium_large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-768x466.png",640,388,true],"large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",640,388,false],"1536x1536":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"2048x2048":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"trp-custom-language-flag":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-18x12.png",18,12,true],"newspack-article-block-landscape-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"newspack-article-block-portrait-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",900,546,false],"newspack-article-block-square-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"newspack-article-block-landscape-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",800,485,false],"newspack-article-block-portrait-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",600,364,false],"newspack-article-block-square-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",800,485,false],"newspack-article-block-landscape-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",600,364,false],"newspack-article-block-portrait-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",450,273,false],"newspack-article-block-square-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",600,364,false],"newspack-article-block-landscape-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",400,243,false],"newspack-article-block-portrait-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",300,182,false],"newspack-article-block-square-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",400,243,false],"newspack-article-block-landscape-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",200,121,false],"newspack-article-block-portrait-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",150,91,false],"newspack-article-block-square-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",200,121,false],"newspack-article-block-uncropped":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"enternews-featured":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp",996,604,false],"enternews-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-720x475.png?crop=1",720,475,true],"enternews-thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-480x315.png?crop=1",480,315,true],"tenweb_optimizer_mobile":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-600x364.png",600,364,true],"tenweb_optimizer_tablet":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe-768x466.png",768,466,true]},"author_info":{"display_name":"EVHNews","author_link":"https:\/\/evhnews.com\/fr\/author\/evhnews\/"},"category_info":"<a href=\"https:\/\/evhnews.com\/fr\/category\/aviation-electrique-hybride\/voitures-volantes-aviation-electrique-hybride\/\" rel=\"category tag\">Electric &amp; Hybrid Aerospace &amp; VTOL Aircrafts<\/a> <a href=\"https:\/\/evhnews.com\/fr\/category\/nouvelle-technologie-de-batterie-ev\/\" rel=\"category tag\">New EV Battery Technology<\/a>","tag_info":"New EV Battery Technology","comment_count":"0","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbbbdx-2O4","amp_enabled":true,"jetpack_featured_media_url":"https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/Eve-Introduces-Aftermarket-Services-Portfolio-for-eVTOLs-Europe.webp","_links":{"self":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/users\/165558846"}],"replies":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/comments?post=10792"}],"version-history":[{"count":2,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10792\/revisions"}],"predecessor-version":[{"id":10795,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/posts\/10792\/revisions\/10795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/media\/10794"}],"wp:attachment":[{"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/media?parent=10792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/categories?post=10792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evhnews.com\/fr\/wp-json\/wp\/v2\/tags?post=10792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}