{"id":10788,"date":"2024-10-23T20:46:08","date_gmt":"2024-10-24T03:46:08","guid":{"rendered":"https:\/\/evhnews.com\/?p=10788"},"modified":"2024-10-23T20:46:08","modified_gmt":"2024-10-24T03:46:08","slug":"la-faa-emette-una-norma-finale-per-la-certificazione-dei-piloti-di-aerotaxi","status":"publish","type":"post","link":"https:\/\/evhnews.com\/it\/2024\/10\/23\/la-faa-emette-una-norma-finale-per-la-certificazione-dei-piloti-di-aerotaxi\/","title":{"rendered":"La FAA emette una norma finale per l'addestramento e la certificazione dei piloti di aerotaxi"},"content":{"rendered":"<p><strong>La norma della Federal Aviation Administration (FAA) \u00e8 considerata l'ultimo tassello del puzzle per l'introduzione in sicurezza degli aerotaxi\/eVTOL nel sistema dello spazio aereo nazionale nel breve termine.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Di Joe Macey AAM International<\/p>\n<p><strong>La Federal Aviation Administration (FAA) ha rivelato che \u00e8 pronta per i taxi aerei, le consegne di merci e una serie di operazioni nelle aree urbane e rurali.<\/strong><\/p>\n<p>Si tratta della prima categoria di aerei civili completamente nuova dall'introduzione degli elicotteri negli anni Quaranta.<\/p>\n<p>L'agenzia ha emesso una norma finale per le qualifiche e l'addestramento che istruttori e piloti devono avere per pilotare i velivoli di questa categoria \"power-lift\", che hanno caratteristiche sia di aerei che di elicotteri.<\/p>\n<p>La norma tratta anche i requisiti operativi, tra cui le altitudini minime di sicurezza e la visibilit\u00e0 richiesta. La norma \u00e8 l'ultimo tassello del puzzle per l'introduzione in sicurezza di questi velivoli nel prossimo futuro. Le opportunit\u00e0 di utilizzo delle operazioni di sollevamento a motore sono di vasta portata, dal trasporto di passeggeri nelle aree urbane, alle operazioni a corto raggio come i servizi di ambulanza aerea e le operazioni di carico, fino al potenziale servizio di comunit\u00e0 pi\u00f9 piccole nel tempo.<\/p>\n<p>L'amministratore della FAA Mike Whitaker ha dichiarato;\u00a0<em>\"La FAA continuer\u00e0 a dare priorit\u00e0 alla sicurezza del nostro sistema, mentre lavoriamo per integrare perfettamente tecnologie e operazioni innovative. Questa norma finale fornisce il quadro necessario per consentire ai velivoli a motore di operare in sicurezza nel nostro spazio aereo. I velivoli a motore sono la prima nuova categoria di velivoli in quasi 80 anni e questa norma storica aprir\u00e0 la strada per consentire in futuro operazioni di mobilit\u00e0 aerea avanzata (AAM) su larga scala\".<\/em><\/p>\n<p>In precedenza, la FAA aveva stabilito di poter certificare i veicoli a propulsione utilizzando le norme esistenti e aveva aggiornato altre norme per consentire l'uso commerciale dei taxi aerei. L'anno scorso l'agenzia ha pubblicato un progetto per il funzionamento dei veicoli della Mobilit\u00e0 Aerea Urbana, che \u00e8 un elemento chiave per la maturazione del concetto generale di AAM.<\/p>\n<p>Era necessario un nuovo regolamento per l'addestramento e le qualifiche dei piloti perch\u00e9 le norme esistenti non riguardavano questa nuova categoria di velivoli, che possono decollare e atterrare in verticale come un elicottero e volare come un aeroplano durante il volo di crociera. La norma fornisce un quadro completo per la certificazione del gruppo iniziale di istruttori e piloti di convertiplani.<\/p>\n<p>La regola:<\/p>\n<ul>\n<li>Apporta modifiche a numerosi regolamenti esistenti e istituisce una Special Federal Aviation Regulation (SFAR) con nuovi requisiti per facilitare la certificazione e la formazione di istruttori e piloti.<\/li>\n<li>Applica i requisiti operativi degli elicotteri ad alcune fasi del volo e adotta un approccio basato sulle prestazioni per alcune regole operative.<\/li>\n<li>Permette ai piloti di addestrarsi al sollevamento a motore con un unico set di comandi di volo; le regole tradizionali richiedono due comandi di volo, uno per l'allievo e uno per l'istruttore.\n<p>... Note da SP,<\/p>\n<p>#EVHNews, #FAA, #SFAR, #eVTOL, #<em>Mobilit\u00e0 aerea avanzata,<\/em><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>The Federal Aviation Administration (FAA) rule is seen as the final piece in the puzzle&#8230;<\/p>","protected":false},"author":165558846,"featured_media":10790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"two_page_speed":[],"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[688379954],"tags":[688387321,688386225,688387319,688387320,688386537],"class_list":["post-10788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flying-cars-electric-hybrid-aviation","tag-advanced-air-mobility","tag-evhnews-2","tag-faa","tag-sfar","tag-evtol"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-150x150.jpg?crop=1",150,150,true],"medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-300x168.jpg",300,168,true],"medium_large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-768x429.jpg",640,358,true],"large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",640,358,false],"1536x1536":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"2048x2048":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"trp-custom-language-flag":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-18x10.jpg",18,10,true],"newspack-article-block-landscape-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"newspack-article-block-portrait-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",900,503,false],"newspack-article-block-square-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"newspack-article-block-landscape-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",800,447,false],"newspack-article-block-portrait-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-square-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",800,447,false],"newspack-article-block-landscape-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-portrait-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",450,251,false],"newspack-article-block-square-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",600,335,false],"newspack-article-block-landscape-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",400,223,false],"newspack-article-block-portrait-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",300,168,false],"newspack-article-block-square-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",400,223,false],"newspack-article-block-landscape-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",200,112,false],"newspack-article-block-portrait-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",150,84,false],"newspack-article-block-square-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",200,112,false],"newspack-article-block-uncropped":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"enternews-featured":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp",1024,572,false],"enternews-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-720x475.jpg?crop=1",720,475,true],"enternews-thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-480x315.jpg?crop=1",480,315,true],"tenweb_optimizer_mobile":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-600x335.jpg",600,335,true],"tenweb_optimizer_tablet":["https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International-768x429.jpg",768,429,true]},"author_info":{"display_name":"EVHNews","author_link":"https:\/\/evhnews.com\/it\/author\/evhnews\/"},"category_info":"<a href=\"https:\/\/evhnews.com\/it\/category\/aviazione-ibrida-elettrica\/auto-volanti-aviazione-elettrica-ibrida\/\" rel=\"category tag\">Electric &amp; Hybrid Aerospace &amp; VTOL Aircrafts<\/a>","tag_info":"Electric &amp; Hybrid Aerospace &amp; VTOL Aircrafts","comment_count":"0","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbbbdx-2O0","amp_enabled":true,"jetpack_featured_media_url":"https:\/\/evhnews.com\/wp-content\/uploads\/2024\/10\/FAA-Issues-Final-Rule-for-Air-Taxi-Pilot-Training-Certification-news-AAM-International.webp","_links":{"self":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/10788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/users\/165558846"}],"replies":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/comments?post=10788"}],"version-history":[{"count":2,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/10788\/revisions"}],"predecessor-version":[{"id":10791,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/10788\/revisions\/10791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/media\/10790"}],"wp:attachment":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/media?parent=10788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/categories?post=10788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/tags?post=10788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}