{"id":7957,"date":"2023-07-07T20:42:03","date_gmt":"2023-07-08T03:42:03","guid":{"rendered":"https:\/\/evhnews.com\/?p=7957"},"modified":"2023-07-07T20:42:03","modified_gmt":"2023-07-08T03:42:03","slug":"gmc-presenta-ledizione-2024-della-canyon-at4x-aev","status":"publish","type":"post","link":"https:\/\/evhnews.com\/it\/2023\/07\/07\/gmc-presenta-ledizione-2024-della-canyon-at4x-aev\/","title":{"rendered":"GMC Unleashes The 2024 Canyon AT4X AEV Edition"},"content":{"rendered":"<ul>\n<li>Partendo dalle solide fondamenta dell'AT4X, l'AEV Edition porta la capacit\u00e0 ancora pi\u00f9 in l\u00e0.<br \/>\ncon rialzo aggiuntivo di 1,5 pollici, pneumatici da 35 pollici e hardware aggiornato.<\/li>\n<\/ul>\n<ul>\n<li>Capacit\u00e0 off-road migliorate abbinate a equipaggiamenti premium firmati GMC<\/li>\n<\/ul>\n<ul>\n<li>La Canyon 2024 include anche caratteristiche tecnologiche aggiornate in tutta la gamma.<\/li>\n<\/ul>\n<p>A meno di un anno dall'introduzione della nuova generazione di Canyon 2023, GMC ha alzato il tiro con il Canyon 2024. Questo modello porta la capacit\u00e0 e la connettivit\u00e0 della Canyon a nuovi livelli con l'introduzione della piattaforma software end-to-end Ultifi e della prima Canyon AT4X AEV Edition.<\/p>\n<p>\"GMC sta dando ai clienti la possibilit\u00e0 di creare il proprio percorso nel settore dei fuoristrada premium\", ha dichiarato Duncan Aldred, vicepresidente globale di Buick-GMC. \"GMC Sierra LD e HD AT4X AEV Edition hanno fornito ci\u00f2 che i clienti cercavano nel settore dei fuoristrada e ora stiamo applicando la stessa formula alla prossima generazione di Canyon\".<\/p>\n<p>Introdotte per la prima volta sulla GMC Sierra 1500 del 2023, le edizioni AEV sono ora disponibili in tutta la gamma di autocarri GMC, a sostegno dell'attenzione del marchio per la fornitura di autocarri premium, avanzati e autenticamente capaci in Nord America.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"7960\" data-permalink=\"https:\/\/evhnews.com\/it\/2023\/07\/07\/gmc-presenta-ledizione-2024-della-canyon-at4x-aev\/gmc-unleashes-the-2024-canyon-at4x-aev-edition-front\/\" data-orig-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front.jpg\" data-orig-size=\"3500,2333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GMC Unleashes the 2024 Canyon AT4X AEV Edition Front\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-1024x683.jpg\" class=\"aligncenter size-large wp-image-7960\" src=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-1024x683.jpg 1024w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-300x200.jpg 300w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-768x512.jpg 768w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-1536x1024.jpg 1536w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-2048x1365.jpg 2048w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-1200x800.jpg 1200w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-Front-600x400.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<h6 style=\"text-align: center;\"><img decoding=\"async\" data-attachment-id=\"7962\" data-permalink=\"https:\/\/evhnews.com\/it\/2023\/07\/07\/gmc-presenta-ledizione-2024-della-canyon-at4x-aev\/gmc-unleashes-the-2024-canyon-at4x-aev-edition-interior\/\" data-orig-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior.jpg\" data-orig-size=\"3500,2333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GMC Unleashes the 2024 Canyon AT4X AEV Edition interior\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-1024x683.jpg\" class=\"aligncenter size-large wp-image-7962\" src=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-1024x683.jpg 1024w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-300x200.jpg 300w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-768x512.jpg 768w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-1536x1024.jpg 1536w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-2048x1365.jpg 2048w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-1200x800.jpg 1200w, https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-interior-600x400.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><em>Credito d'immagine: GM Media<\/em><\/h6>\n<p><strong><br \/>\nPortare Canyon al livello successivo<\/strong><\/p>\n<p>Il Canyon di nuova generazione continua a perseguire il suo obiettivo di diventare il pi\u00f9 capace e premium fuoristrada di medie dimensioni del segmento. La Canyon AT4X AEV Edition 2024 porta la potenza e la versatilit\u00e0 della Canyon AT4X a nuovi livelli con un assetto ancora pi\u00f9 deciso, un hardware migliorato e ulteriori aggiornamenti al telaio del veicolo, tra cui:<\/p>\n<ul>\n<li>Pneumatici Goodyear Wrangler Territory MT da 35 pollici con supporto AEV aggiuntivo per la ruota di scorta verticale nel vano bagagli<\/li>\n<\/ul>\n<ul>\n<li>Fascia anteriore aggiornata e parafanghi pi\u00f9 grandi per consentire carreggiate pi\u00f9 larghe e un'altezza da terra di 12,2 pollici, la migliore della categoria.<sup>1<\/sup><\/li>\n<\/ul>\n<ul>\n<li>Sollevamento di 4,5 pollici (114 mm) installato in fabbrica - 1,5 pollici (38 mm) in pi\u00f9 rispetto al Canyon AT4X<\/li>\n<\/ul>\n<ul>\n<li>Paraurti anteriori e posteriori in acciaio stampato AEV per impieghi gravosi con punti di recupero per impieghi gravosi e paraurti anteriore con verricello<\/li>\n<\/ul>\n<ul>\n<li>Cinque skid plate in acciaio al boro ad altissima resistenza e stampati a caldo (posizionati lungo il radiatore, la scatola dello sterzo, la trasmissione e il transfer case, il serbatoio del carburante e il differenziale posteriore) per una protezione ottimizzata del sottoscocca<\/li>\n<\/ul>\n<ul>\n<li>L'aggiunta di tre interruttori di comando ausiliari di serie che consentono l'integrazione di accessori off-road e overlanding.<\/li>\n<\/ul>\n<ul>\n<li>Esclusivi cerchi AEV con beadlock Salta<\/li>\n<\/ul>\n<ul>\n<li>Marchio AEV su tutto il veicolo, compresi i paraurti, i poggiatesta ricamati e le fodere per il pavimento per tutte le stagioni<\/li>\n<\/ul>\n<p>\"Il GMC Canyon AT4X \u00e8 una piattaforma incredibilmente formidabile quando si tratta di prestazioni e capacit\u00e0 su strada e fuoristrada\", ha dichiarato Dave Harriton, CEO e fondatore di AEV. \"Abbiamo adottato il nostro approccio caratteristico per contribuire a elevare le capacit\u00e0 fuoristradistiche intrinseche del Canyon AT4X a un livello superiore. Questo veicolo soddisfa le esigenze di tutti gli appassionati di fuoristrada che cercano lusso, tecnologia e capacit\u00e0 in una piattaforma di medie dimensioni\".<\/p>\n<p>Con un sollevamento pi\u00f9 deciso e un nuovo hardware AEV, il Canyon AT4X AEV Edition 2024 pu\u00f2 ora raggiungere un angolo di avvicinamento anteriore di 38,2 gradi, un angolo di stacco di 26,9 gradi e un angolo di partenza ottimizzato di 26,0 gradi. Questi paraurti sono progettati per l'off-road, con punti di recupero posteriori fusi per impieghi gravosi e capacit\u00e0 di verricello anteriore integrati, oltre a garantire un'eccellente durata e resistenza alla corrosione. Il paraurti posteriore \u00e8 inoltre dotato di angoli rimovibili per facilitarne la rimozione e la reinstallazione quando si percorrono i sentieri.<\/p>\n<p><strong>Tecnologia Next-Gen<\/strong><\/p>\n<p>Canyon continua a rafforzare la sua suite di tecnologie avanzate. Per il modello 2024, la modalit\u00e0 di guida Baja di Canyon - disponibile esclusivamente su Canyon AT4X e AT4X AEV Edition - \u00e8 stata migliorata per includere una nuova funzione di launch control, che consente ai conducenti di premere contemporaneamente i pedali del freno e dell'acceleratore, per poi rilasciare il pedale del freno, migliorando l'accelerazione su strada e in fuoristrada. Questa funzione intelligente di controllo della partenza apprende la superficie di guida e pu\u00f2 regolare di conseguenza il regime e la coppia del motore per migliorare le prestazioni successive nei lanci futuri.<sup>2<\/sup>.<\/p>\n<p>Inoltre, tutti i Canyon 2024 potranno aggiungere nuove funzionalit\u00e0 e aggiornamenti software nel tempo grazie all'introduzione della piattaforma Ultifi di GM. Ultifi \u00e8 la nuova piattaforma software end-to-end per veicoli di GM che consente di fornire funzionalit\u00e0 e servizi ai clienti via etere, il che significa che questi ausili per fuoristrada possono essere aggiornati e aggiungere nuove esperienze in futuro.<\/p>\n<p>\"Il mercato continua a registrare un'impennata di interesse per lo spazio delle medie dimensioni\", ha dichiarato Aldred. \"I clienti vogliono qualcosa di capace e premium, con una tecnologia mirata che permetta loro di uscire dai sentieri battuti. La prossima generazione di GMC Canyon e la nuovissima Canyon AT4X AEV Edition saranno tutto questo e molto di pi\u00f9\".<\/p>\n<p><strong>In arrivo nel corso dell'anno<\/strong><\/p>\n<p>La Canyon di nuova generazione viene prodotta nello stabilimento GM di Wentzville, nel Missouri.<sup>3<\/sup>. La Canyon AT4X AEV Edition 2024 dovrebbe essere disponibile per gli ordini dei clienti nel corso dell'anno.<\/p>\n<p><sup>1<\/sup>Sulla base degli ultimi dati competitivi disponibili.<br \/>\n<sub>2<\/sub>Alcuni aggiornamenti e funzioni premium possono avere un costo aggiuntivo.<br \/>\n<sub>3<\/sub>Di componenti di provenienza globale<\/p>\n<p>...note da SP<br \/>\n<img decoding=\"async\" data-attachment-id=\"7554\" data-permalink=\"https:\/\/evhnews.com\/it\/2023\/05\/10\/all-new-kia-ev9-suv-set-for-nationwide-electrify-expo-tour\/evh-news-lighting-bolt-logo-3\/\" data-orig-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/05\/EVH-News-Lighting-Bolt-Logo-.jpg\" data-orig-size=\"100,100\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1575197468&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"EVH News-Lighting-Bolt-Logo-\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/05\/EVH-News-Lighting-Bolt-Logo-.jpg\" class=\"size-full wp-image-7554 alignleft\" src=\"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/05\/EVH-News-Lighting-Bolt-Logo-.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Building off the strong AT4X foundation, AEV Edition takes capability even further with additional 1.5-inch&#8230;<\/p>","protected":false},"author":165558846,"featured_media":7959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"two_page_speed":[],"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[688386203],"tags":[],"class_list":["post-7957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-semi-trucks-electric-commercial-semi-trucks"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg",3500,2333,false],"thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-150x150.jpg?crop=1",150,150,true],"medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-300x200.jpg",300,200,true],"medium_large":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-768x512.jpg",640,427,true],"large":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-2048x1365.jpg",2048,1365,true],"trp-custom-language-flag":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg",18,12,false],"newspack-article-block-landscape-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1200x900.jpg?crop=1",1200,900,true],"newspack-article-block-portrait-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-900x1200.jpg?crop=1",900,1200,true],"newspack-article-block-square-large":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1200x1200.jpg?crop=1",1200,1200,true],"newspack-article-block-landscape-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-800x600.jpg?crop=1",800,600,true],"newspack-article-block-portrait-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-600x800.jpg?crop=1",600,800,true],"newspack-article-block-square-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-800x800.jpg?crop=1",800,800,true],"newspack-article-block-landscape-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg",600,400,false],"newspack-article-block-portrait-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg",450,300,false],"newspack-article-block-square-intermediate":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg",600,400,false],"newspack-article-block-landscape-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-400x300.jpg?crop=1",400,300,true],"newspack-article-block-portrait-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-300x400.jpg?crop=1",300,400,true],"newspack-article-block-square-small":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-400x400.jpg?crop=1",400,400,true],"newspack-article-block-landscape-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-200x150.jpg?crop=1",200,150,true],"newspack-article-block-portrait-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-150x200.jpg?crop=1",150,200,true],"newspack-article-block-square-tiny":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-200x200.jpg?crop=1",200,200,true],"newspack-article-block-uncropped":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1200x800.jpg",1200,800,true],"enternews-featured":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-1024x683.jpg",1024,683,true],"enternews-medium":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-720x475.jpg?crop=1",720,475,true],"enternews-thumbnail":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-480x315.jpg?crop=1",480,315,true],"tenweb_optimizer_mobile":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-600x400.jpg",600,400,true],"tenweb_optimizer_tablet":["https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition-768x512.jpg",768,512,true]},"author_info":{"display_name":"EVHNews","author_link":"https:\/\/evhnews.com\/it\/author\/evhnews\/"},"category_info":"<a href=\"https:\/\/evhnews.com\/it\/category\/semirimorchi-commerciali-elettrici\/semirimorchi-elettrici-semirimorchi-commerciali\/\" rel=\"category tag\">Electric Trucks<\/a>","tag_info":"Electric Trucks","comment_count":"0","jetpack_featured_media_url":"https:\/\/evhnews.com\/wp-content\/uploads\/2023\/07\/GMC-Unleashes-the-2024-Canyon-AT4X-AEV-Edition.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbbbdx-24l","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/7957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/users\/165558846"}],"replies":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/comments?post=7957"}],"version-history":[{"count":3,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/7957\/revisions"}],"predecessor-version":[{"id":7963,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/posts\/7957\/revisions\/7963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/media\/7959"}],"wp:attachment":[{"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/media?parent=7957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/categories?post=7957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evhnews.com\/it\/wp-json\/wp\/v2\/tags?post=7957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}